{"id":3476,"date":"2023-02-10T15:08:13","date_gmt":"2023-02-10T15:08:13","guid":{"rendered":"https:\/\/doctormarcosales.com\/specialties\/evisceracion\/"},"modified":"2023-09-29T10:34:40","modified_gmt":"2023-09-29T10:34:40","slug":"evisceration","status":"publish","type":"page","link":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/","title":{"rendered":"Evisceration"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221;][vc_column offset=&#8221;vc_col-lg-6 vc_col-md-6&#8243;][vc_column_text]Evisceration is the procedure performed in cases of irreparable eye injuries, or in cases of painful blind eyes with no possibility of visual recovery, in which the eye is emptied and filled with an intraorbital prosthesis. This sphere-shaped intraorbital prosthesis is placed inside the orbit, covered by the normal covering of the eye and restores the volume lost due to the missing eye. On the outside, an external prosthesis is placed, which is customised and painted with the colour and features of the other eye, so that it looks aesthetically like a normal eye.<\/p>\n<p>It is a surgery that replaces a blind, painful and aesthetically unfavourable eye with a cavity with a prosthesis that is still blind, but painless and aesthetically unnoticeable in many cases.<\/p>\n<p>The surgery can be performed under local anaesthesia on an outpatient basis, without the need for hospitalisation. The postoperative period is uncomfortable during the first week due to inflammation, and generally a provisional prosthesis can be fitted after 2-3 weeks. The definitive (personalised) prosthesis is usually fitted one month after surgery.<\/p>\n<p>Enucleation is like evisceration, but instead of emptying the eye, the entire eye is removed. It is generally reserved for cases of intraocular tumours in which evisceration is contraindicated.[\/vc_column_text][\/vc_column][vc_column offset=&#8221;vc_col-lg-6 vc_col-md-6&#8243; css=&#8221;.vc_custom_1634645121029{padding-bottom: 60px !important;}&#8221;]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div {\n  width: 40px;\n  height: 40px;\n  border-radius: 500px;\n}\n.dt-arrow-border-on.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div:not(:hover):before {\n  border-width: 0px;\n}\n.dt-arrow-hover-border-on.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div:hover:after {\n  border-width: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div.owl-prev {\n  top: calc(100% + 20px);\n  left: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div.owl-next {\n  top: calc(100% + 20px);\n  right: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav i {\n  font-size: 24px;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div:not(:hover) i,\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div:not(:hover) i:before {\n  color: rgba(0,0,0,0.2);\n  background: none;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div:hover i,\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.owl-carousel .owl-nav div:hover i:before {\n  color: rgba(0,0,0,0.3);\n  background: none;\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dots {\n  top: calc(100% + 20px);\n  left: 50%;\n  transform: translateX(calc(-50% + 0px));\n}\n@media all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dots {\n    transform: translateX(-50%);\n    margin-left: 0px;\n  }\n}\n.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot {\n  width: 8px;\n  height: 8px;\n  margin: 0 6px;\n}\n.bullets-scale-up.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):not(:hover) span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-scale-up.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):hover span,\n.bullets-scale-up.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot.active span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):not(:hover) span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):hover span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot.active span {\n  box-shadow: 0 0 0 2px rgba(0,0,0,0.3);\n}\n.bullets-fill-in.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):not(:hover) span {\n  box-shadow: inset 0 0 0 2px rgba(0,0,0,0.2);\n}\n.bullets-fill-in.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):hover span {\n  box-shadow: inset 0 0 0 2px rgba(0,0,0,0.3);\n}\n.bullets-fill-in.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot.active span {\n  box-shadow: inset 0 0 0 20px rgba(0,0,0,0.3);\n}\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):not(:hover) span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):hover span,\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot.active span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot.active {\n  box-shadow: 0 0 0 2px rgba(0,0,0,0.3);\n}\n.bullets-ubax.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-ubax.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot.active span {\n  border-color: rgba(0,0,0,0.3);\n}\n.bullets-ubax.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):hover span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-etefu.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-etefu.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot:not(.active):hover span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-etefu.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot span:before {\n  background: rgba(0,0,0,0.3);\n}\n.accent-gradient .bullets-etefu.carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 .owl-dot span:before {\n  background: rgba(0,0,0,0.3);\n}\n@media screen and (max-width: 778px) {\n  .carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.hide-arrows .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.reposition-arrows .owl-nav .owl-prev {\n    top: calc(100% + 20px);\n    left: 10px;\n  }\n  .carousel-shortcode.carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051.reposition-arrows .owl-nav .owl-next {\n    top: calc(100% + 20px);\n    right: 10px;\n  }\n}<\/style><div class=\"owl-carousel carousel-shortcode dt-owl-carousel-call carousel-shortcode-id-908ac09cc17e79a6a0a42a9245ae2051 bullets-scale-up arrows-bg-off disable-arrows-hover-bg arrows-hover-bg-off  \" data-scroll-mode=\"1\" data-col-num=\"1\" data-wide-col-num=\"1\" data-laptop-col=\"1\" data-h-tablet-columns-num=\"1\" data-v-tablet-columns-num=\"1\" data-phone-columns-num=\"1\" data-auto-height=\"true\" data-col-gap=\"30\" data-stage-padding=\"0\" data-speed=\"600\" data-autoplay=\"false\" data-autoplay_speed=\"6000\" data-arrows=\"true\" data-bullet=\"true\" data-next-icon=\"icon-ar-013-r\" data-prev-icon=\"icon-ar-013-l\">[vc_single_image image=&#8221;2371&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;2372&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;]<\/div><style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div {\n  width: 40px;\n  height: 40px;\n  border-radius: 500px;\n}\n.dt-arrow-border-on.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div:not(:hover):before {\n  border-width: 0px;\n}\n.dt-arrow-hover-border-on.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div:hover:after {\n  border-width: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div.owl-prev {\n  top: calc(100% + 20px);\n  left: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div.owl-next {\n  top: calc(100% + 20px);\n  right: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav i {\n  font-size: 24px;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div:not(:hover) i,\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div:not(:hover) i:before {\n  color: rgba(0,0,0,0.2);\n  background: none;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div:hover i,\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.owl-carousel .owl-nav div:hover i:before {\n  color: rgba(0,0,0,0.3);\n  background: none;\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dots {\n  top: calc(100% + 20px);\n  left: 50%;\n  transform: translateX(calc(-50% + 0px));\n}\n@media all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dots {\n    transform: translateX(-50%);\n    margin-left: 0px;\n  }\n}\n.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot {\n  width: 8px;\n  height: 8px;\n  margin: 0 6px;\n}\n.bullets-scale-up.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):not(:hover) span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-scale-up.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):hover span,\n.bullets-scale-up.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot.active span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):not(:hover) span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):hover span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot.active span {\n  box-shadow: 0 0 0 2px rgba(0,0,0,0.3);\n}\n.bullets-fill-in.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):not(:hover) span {\n  box-shadow: inset 0 0 0 2px rgba(0,0,0,0.2);\n}\n.bullets-fill-in.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):hover span {\n  box-shadow: inset 0 0 0 2px rgba(0,0,0,0.3);\n}\n.bullets-fill-in.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot.active span {\n  box-shadow: inset 0 0 0 20px rgba(0,0,0,0.3);\n}\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):not(:hover) span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):hover span,\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot.active span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-small-dot-stroke.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot.active {\n  box-shadow: 0 0 0 2px rgba(0,0,0,0.3);\n}\n.bullets-ubax.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-ubax.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot.active span {\n  border-color: rgba(0,0,0,0.3);\n}\n.bullets-ubax.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):hover span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-etefu.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot span {\n  background: rgba(0,0,0,0.2);\n}\n.bullets-etefu.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot:not(.active):hover span {\n  background: rgba(0,0,0,0.3);\n}\n.bullets-etefu.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot span:before {\n  background: rgba(0,0,0,0.3);\n}\n.accent-gradient .bullets-etefu.carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e .owl-dot span:before {\n  background: rgba(0,0,0,0.3);\n}\n@media screen and (max-width: 778px) {\n  .carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.hide-arrows .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.reposition-arrows .owl-nav .owl-prev {\n    top: calc(100% + 20px);\n    left: 10px;\n  }\n  .carousel-shortcode.carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e.reposition-arrows .owl-nav .owl-next {\n    top: calc(100% + 20px);\n    right: 10px;\n  }\n}<\/style><div class=\"owl-carousel carousel-shortcode dt-owl-carousel-call carousel-shortcode-id-2ba88ce3a8b311f72be8ca7b7abb8a3e bullets-scale-up arrows-bg-off disable-arrows-hover-bg arrows-hover-bg-off  vc_custom_1676041725711 \" data-scroll-mode=\"1\" data-col-num=\"1\" data-wide-col-num=\"1\" data-laptop-col=\"1\" data-h-tablet-columns-num=\"1\" data-v-tablet-columns-num=\"1\" data-phone-columns-num=\"1\" data-auto-height=\"true\" data-col-gap=\"30\" data-stage-padding=\"0\" data-speed=\"600\" data-autoplay=\"false\" data-autoplay_speed=\"6000\" data-arrows=\"true\" data-bullet=\"true\" data-next-icon=\"icon-ar-013-r\" data-prev-icon=\"icon-ar-013-l\">[vc_single_image image=&#8221;2370&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;2369&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;]<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; gap=&#8221;35&#8243; css=&#8221;.vc_custom_1677601023380{margin-top: 40px !important;margin-bottom: -80px !important;padding-top: 40px !important;padding-bottom: 40px !important;background-color: #ebe7e4 !important;}&#8221;][vc_column]<div id=\"ultimate-heading-27166a04a21e245fa\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-27166a04a21e245fa uvc-3954 accent-border-color\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-27166a04a21e245fa h2'  data-responsive-json-new='{\"font-size\":\"desktop:38px;\",\"line-height\":\"desktop:48px;\"}' ><h2 style=\"--font-weight:theme;margin-bottom:10px;\">CONTACT US<\/h2><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3034.5391623156524!2d-3.7207495840544698!3d40.4854590793572!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd42298ddaac29b9%3A0xfca42f46f41ac8c9!2sC.%20del%20Valle%20de%20Pinares%20Llanos%2C%203%2C%2028035%20Madrid!5e0!3m2!1ses!2ses!4v1675767263645!5m2!1ses!2ses\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/vc_column_text][vc_column_text]<strong>IMO Grupo Miranza Madrid<\/strong><\/p>\n<p>C\/ del Valle Pinares Llanos, 3, 28305 Madrid<\/p>\n<p>910 783 783[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1677598913734{padding-right: 50px !important;padding-left: 50px !important;}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3452-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"3452\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/3476#wpcf7-f3452-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3452\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3452-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<h2 style=\"text-align: center;\", font-weight: bold;>MAKE AN APPOINTMENT NOW!\n<\/h2>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"3\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Reason for appointment\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-19\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-19\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I consent to the processing of my data by Dr. Marco Sales for the purpose of managing the appointment request. <br>More information in our <a href=\"\/politica-de-privacidad\/\" target=\"_blank\" text-style: bold\">Privacy Policy <\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-453\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-453[]\" value=\"I wish to receive information about news and promotions from Dr. Marco Sales\" \/><span class=\"wpcf7-list-item-label\">I wish to receive information about news and promotions from Dr. Marco Sales<\/span><\/span><\/span><\/span>\n<\/p>\n<div align=\"center\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ASK FOR MORE INFORMATION\" \/>\n\t<\/p>\n<\/div>\n<p><script>\ndocument.addEventListener( 'wpcf7mailsent', function( event ) {\n location = '\/gracias-por-el-mensaje\/';\n}, false );\n<\/script>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"125\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221;][vc_column offset=&#8221;vc_col-lg-6 vc_col-md-6&#8243;][vc_column_text]Evisceration is the procedure performed in cases of irreparable eye injuries, or in cases of painful blind eyes with no possibility of visual recovery, in which the eye is emptied and filled with an intraorbital prosthesis. This sphere-shaped intraorbital prosthesis is placed inside the orbit, covered by the normal covering of&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3394,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3476","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evisceration - Dr. Marco Sales<\/title>\n<meta name=\"description\" content=\"Evisceraci\u00f3n es una cirug\u00eda en la que se extrae el contenido del ojo, preservando la escler\u00f3tica, en casos graves.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evisceration - Dr. Marco Sales\" \/>\n<meta property=\"og:description\" content=\"Evisceraci\u00f3n es una cirug\u00eda en la que se extrae el contenido del ojo, preservando la escler\u00f3tica, en casos graves.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Marco Sales\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T10:34:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/\",\"url\":\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/\",\"name\":\"Evisceration - Dr. Marco Sales\",\"isPartOf\":{\"@id\":\"https:\/\/doctormarcosales.com\/#website\"},\"datePublished\":\"2023-02-10T15:08:13+00:00\",\"dateModified\":\"2023-09-29T10:34:40+00:00\",\"description\":\"Evisceraci\u00f3n es una cirug\u00eda en la que se extrae el contenido del ojo, preservando la escler\u00f3tica, en casos graves.\",\"breadcrumb\":{\"@id\":\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/doctormarcosales.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Specialties\",\"item\":\"https:\/\/doctormarcosales.com\/en\/specialties\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evisceration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/doctormarcosales.com\/#website\",\"url\":\"https:\/\/doctormarcosales.com\/\",\"name\":\"Dr. Marco Sales\",\"description\":\"M\u00e9dico oftalm\u00f3logo especializado en Blefaroplastia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/doctormarcosales.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evisceration - Dr. Marco Sales","description":"Evisceraci\u00f3n es una cirug\u00eda en la que se extrae el contenido del ojo, preservando la escler\u00f3tica, en casos graves.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/","og_locale":"en_US","og_type":"article","og_title":"Evisceration - Dr. Marco Sales","og_description":"Evisceraci\u00f3n es una cirug\u00eda en la que se extrae el contenido del ojo, preservando la escler\u00f3tica, en casos graves.","og_url":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/","og_site_name":"Dr. Marco Sales","article_modified_time":"2023-09-29T10:34:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/","url":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/","name":"Evisceration - Dr. Marco Sales","isPartOf":{"@id":"https:\/\/doctormarcosales.com\/#website"},"datePublished":"2023-02-10T15:08:13+00:00","dateModified":"2023-09-29T10:34:40+00:00","description":"Evisceraci\u00f3n es una cirug\u00eda en la que se extrae el contenido del ojo, preservando la escler\u00f3tica, en casos graves.","breadcrumb":{"@id":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/doctormarcosales.com\/en\/specialties\/evisceration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/doctormarcosales.com\/en\/"},{"@type":"ListItem","position":2,"name":"Specialties","item":"https:\/\/doctormarcosales.com\/en\/specialties\/"},{"@type":"ListItem","position":3,"name":"Evisceration"}]},{"@type":"WebSite","@id":"https:\/\/doctormarcosales.com\/#website","url":"https:\/\/doctormarcosales.com\/","name":"Dr. Marco Sales","description":"M\u00e9dico oftalm\u00f3logo especializado en Blefaroplastia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/doctormarcosales.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/pages\/3476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/comments?post=3476"}],"version-history":[{"count":2,"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/pages\/3476\/revisions"}],"predecessor-version":[{"id":3560,"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/pages\/3476\/revisions\/3560"}],"up":[{"embeddable":true,"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/pages\/3394"}],"wp:attachment":[{"href":"https:\/\/doctormarcosales.com\/en\/wp-json\/wp\/v2\/media?parent=3476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}